{"id":82744,"date":"2026-07-14T11:20:00","date_gmt":"2026-07-14T09:20:00","guid":{"rendered":"https:\/\/neueswochenblatt.pl\/?p=82744"},"modified":"2026-07-14T11:21:06","modified_gmt":"2026-07-14T09:21:06","slug":"glaube-und-nationale-zugehoerigkeit-vereint","status":"publish","type":"post","link":"https:\/\/neueswochenblatt.pl\/de\/glaube-und-nationale-zugehoerigkeit-vereint\/","title":{"rendered":"Glaube und nationale Zugeh\u00f6rigkeit vereint"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Vor \u00fcber 750 Jahren wurde der Marienkult in Wartha erstmals urkundlich erw\u00e4hnt. Im Laufe der Jahrhunderte entwickelte sich die Tradition, zur Wallfahrtskirche Mari\u00e4 Heimsuchung zu pilgern. Viele Menschen nahmen weite Wege auf sich, um diesen besonderen Ort zu besuchen. Der Grund daf\u00fcr ist die \u00fcber 1000 Jahre alte Marienfigur, der zahlreiche Wunder zugeschrieben werden. Auch heute zieht Wartha jedes Jahr zahlreiche Pilger an.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>Eine dieser Wallfahrten ist die Wallfahrt der deutschen Minderheit, die traditionell am zweiten Sonntag im Juli stattfindet. In diesem Jahr versammelten sich die Gl\u00e4ubigen am 12. Juli in Wartha. Deutsch, Polnisch und Schlesisch waren gleicherma\u00dfen zu h\u00f6ren und spiegelten die sprachliche Vielfalt der Teilnehmer wider.<\/p>\n<p>Die Heilige Messe wurde von zwei Priestern zelebriert und feierlich vom Blasorchester aus Krappitz sowie vom Chor aus Paulsdorf musikalisch er\u00f6ffnet. Anschlie\u00dfend begr\u00fc\u00dfte der Seelsorger der deutschen Minderheit in der Erzdi\u00f6zese Breslau, Pater Marian Bernard Arndt, alle Pilger. An der Orgel spielte Hubert Prochota.<\/p>\n<div id=\"attachment_82746\" style=\"width: 778px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82746\" class=\"size-large wp-image-82746\" src=\"https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/Organy-768x1024.jpeg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/Organy-768x1024.jpeg 768w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/Organy-225x300.jpeg 225w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/Organy-1152x1536.jpeg 1152w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/Organy.jpeg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><p id=\"caption-attachment-82746\" class=\"wp-caption-text\"><br \/>Foto: Die Orgel, die im 18. Jahrhundert von Joseph Eberhard aus Breslau erbaut wurde.<br \/>Foto: Lea Herbst<\/p><\/div>\n<p>W\u00e4hrend seiner zweisprachigen Predigt zitierte Pfarrer Andrzej Anderwald, Seelsorger der deutschen Minderheit in der Di\u00f6zese Oppeln, den j\u00fcdischen Philosophen Martin Buber mit den Worten: \u201eAlles wirkliche Leben ist Begegnung.\u201c Er bezog dieses Zitat auf die Begegnung Marias mit Elisabeth aus dem Lukasevangelium. Gleichzeitig erinnerte er daran, dass jeder Mensch solche pr\u00e4genden Begegnungen erlebt \u2013 sei es die erste Liebe, eine Freundschaft oder andere wichtige Momente im Leben. Auch diese Wallfahrt sei eine solche Begegnung, die Menschen im Glauben und in ihrer Gemeinschaft verbinde.<\/p>\n<h2>Kleine Figur, gro\u00dfe Bedeutung \u2013 die Marienfigur von Wartha<\/h2>\n<p>Die nur 43 Zentimeter gro\u00dfe Marienfigur mag auf den ersten Blick unscheinbar wirken, doch sie geh\u00f6rt zu den \u00e4ltesten ihrer Art. Untersuchungen zufolge ist sie mehr als 1000 Jahre alt. Woher dieses romanische Kunstwerk urspr\u00fcnglich stammt, ist bis heute nicht gekl\u00e4rt. Sicher ist jedoch, dass sich die Figur bereits um das Jahr 1110 in Wartha befand.<\/p>\n<div id=\"attachment_82755\" style=\"width: 778px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82755\" class=\"size-large wp-image-82755\" src=\"https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/Figurka-z-bliska-768x1024.jpeg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/Figurka-z-bliska-768x1024.jpeg 768w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/Figurka-z-bliska-225x300.jpeg 225w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/Figurka-z-bliska-1152x1536.jpeg 1152w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/Figurka-z-bliska.jpeg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><p id=\"caption-attachment-82755\" class=\"wp-caption-text\">Die Marienfigur, die w\u00e4hrend der Wallfahrt der deutschen Minderheit zur Verehrung ausgestellt wurde.<br \/>Foto: Lea Herbst<\/p><\/div>\n<p>Im Laufe der Jahrhunderte wurde sie immer wieder vor Gefahren in Sicherheit gebracht \u2013 unter anderem w\u00e4hrend der Hussitenkriege, in der Zeit der Reformation sowie w\u00e4hrend der schwedischen Kriege. Sie \u00fcberstand au\u00dferdem den verheerenden Brand der Kirche und gro\u00dfer Teile der Stadt im 18. Jahrhundert.<\/p>\n<blockquote><p>\u201eMusik, Sprache und Glaube verbinden Menschen \u00fcber Generationen hinweg. Diese Wallfahrt zeigt, dass unsere Traditionen auch heute noch lebendig sind.\u201c<\/p><\/blockquote>\n<p>Am 3. Juli 1966 wurde die Marienfigur von Erzbischof Boles\u0142aw Kominek feierlich gekr\u00f6nt. Rund 150.000 Pilger nahmen damals an den Feierlichkeiten teil. Am 3. Juli 2026 beging die Pfarrgemeinde das 60. Jubil\u00e4um dieser Kr\u00f6nung. Aus diesem Anlass wurden zus\u00e4tzlich Reliquien aus dem Loretohaus sowie der heiligen Alfons, Klemens und Gerhard im Sockel der Figur eingesetzt. Die besondere Bedeutung der Kirche wurde bereits 2008 unterstrichen, als Papst Benedikt XVI. sie zur Basilica minor erhob.<\/p>\n<h2>Pilger teilen ihre Erfahrungen<\/h2>\n<p>Pater Marian Bernard Arndt, der seit mehr als 50 Jahren als Priester t\u00e4tig ist, erz\u00e4hlte im Gespr\u00e4ch mit Neues Wochenblatt.pl nach der Messe, wie er Wartha kennenlernte:<\/p>\n<blockquote><p>\u201eAuf meine Priesterweihe habe ich mich in Glatz vorbereitet. Damals lernte ich Wartha kennen und nahm an den Wallfahrten teil. Es waren noch keine deutschen Wallfahrten. F\u00fcr mich war damals alles neu, aber die Basilika und die Marienfigur haben mich sofort fasziniert. Dass es auch Wallfahrten der deutschen Minderheit gibt, habe ich erst sp\u00e4ter erfahren.\u201c<\/p><\/blockquote>\n<div id=\"attachment_82753\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82753\" class=\"size-large wp-image-82753\" src=\"https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/DO-GRAFIKI-NA-FB-Fotografia-grupowa-1024x768.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/DO-GRAFIKI-NA-FB-Fotografia-grupowa-1024x768.jpeg 1024w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/DO-GRAFIKI-NA-FB-Fotografia-grupowa-300x225.jpeg 300w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/DO-GRAFIKI-NA-FB-Fotografia-grupowa-768x576.jpeg 768w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/DO-GRAFIKI-NA-FB-Fotografia-grupowa-1536x1152.jpeg 1536w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/DO-GRAFIKI-NA-FB-Fotografia-grupowa.jpeg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-82753\" class=\"wp-caption-text\">Ein Gruppenbild mit einem Teil der Teilnehmer der Wallfahrt.<br \/>Foto: Lea Herbst<\/p><\/div>\n<p>Seit rund zwanzig Jahren organisiert Pater Arndt die Wallfahrt der deutschen Minderheit. Anfangs sei die Gruppe noch klein gewesen. Umso mehr freue er sich dar\u00fcber, wie sich die Wallfahrt im Laufe der Jahre entwickelt habe.<\/p>\n<p>Auf die Frage nach der Situation nach dem Zweiten Weltkrieg erkl\u00e4rte er:<\/p>\n<blockquote><p>\u201eDie deutsche Sprache und die deutsche Seelsorge waren in Oberschlesien verboten. In der Erzdi\u00f6zese Breslau wurden sie jedoch geduldet.\u201c<\/p><\/blockquote>\n<p>In den 1970er Jahren seien viele Gl\u00e4ubige aus Niederschlesien und vereinzelt auch aus Oberschlesien nach Wartha gekommen. Der zweite Sonntag im Juli sei bewusst gew\u00e4hlt worden, weil an diesem Tag fr\u00fcher das Fest Mari\u00e4 Heimsuchung gefeiert wurde. Schon vor der politischen Wende habe sich dieser Termin etabliert.<\/p>\n<p>Ein anderer Seelsorger habe ihm erz\u00e4hlt, dass die Kirche in den 1970er Jahren bei den deutschen Wallfahrten bis auf den letzten Platz gef\u00fcllt gewesen sei. Damals sei die Kirche f\u00fcr viele Menschen ein Ort der Freiheit gewesen.<\/p>\n<div id=\"attachment_82760\" style=\"width: 778px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82760\" class=\"size-large wp-image-82760\" src=\"https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/Cala-swiatynia-768x1024.jpeg\" alt=\"\" width=\"768\" height=\"1024\" \/><p id=\"caption-attachment-82760\" class=\"wp-caption-text\">Wallfahrtskirche Mari\u00e4 Heimsuchung in Wartha<br \/>Foto: Lea Herbst<\/p><\/div>\n<p>Auf die Frage nach der Zukunft der Wallfahrt antwortete Pater Arndt:<\/p>\n<blockquote><p>\u201eDamals gab es noch viele deutsche Familien. Viele von ihnen sind inzwischen verstorben oder nach Deutschland ausgewandert. Au\u00dferdem hat sich die Bedeutung der Religion in den vergangenen Jahrzehnten leider ver\u00e4ndert. Daf\u00fcr gibt es viele Gr\u00fcnde.\u201c<\/p><\/blockquote>\n<p>Heute seien die Pilgergruppen zwar kleiner als fr\u00fcher, dennoch n\u00e4hmen die Gl\u00e4ubigen mit gro\u00dfer Freude und gro\u00dfer Treue Jahr f\u00fcr Jahr an der Wallfahrt teil.<\/p>\n<p>Die 91-j\u00e4hrige Doris Stempowska aus Waldenburg erz\u00e4hlte, dass sie \u201eschon immer\u201c an der Wallfahrt teilnehme. Mit einem L\u00e4cheln f\u00fcgte sie hinzu: \u201eNur laufen kann ich nicht mehr.\u201c Gemeinsam mit ihrem Sohn Leopold nahm sie jedoch an der gesamten Messe sowie an der anschlie\u00dfenden Verehrung der Marienfigur teil. Trotz ihres hohen Alters beeindruckte sie mit ihrem Humor und ihrem ausgezeichneten Ged\u00e4chtnis. Sicher h\u00e4tte sie noch viele spannende Geschichten erz\u00e4hlen k\u00f6nnen \u2013 doch daf\u00fcr reichte die Zeit leider nicht.<\/p>\n<h2>Ein leckeres Souvenir zum Mitbringen<\/h2>\n<p>Nach einer langen Wallfahrt freuen sich viele Pilger auf eine kleine St\u00e4rkung. Eine besondere Tradition in Wartha ist dabei der Kauf von Lebkuchen. Das Geb\u00e4ck eignet sich daf\u00fcr besonders gut: Es ist lange haltbar und entwickelt mit der Zeit sogar ein noch intensiveres Aroma.<\/p>\n<div id=\"attachment_82749\" style=\"width: 778px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82749\" class=\"size-large wp-image-82749\" src=\"https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/znak-piekarni-768x1024.jpeg\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/znak-piekarni-768x1024.jpeg 768w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/znak-piekarni-225x300.jpeg 225w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/znak-piekarni-1152x1536.jpeg 1152w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/znak-piekarni.jpeg 1530w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><p id=\"caption-attachment-82749\" class=\"wp-caption-text\">Das 2014 von Liebhabern angebrachte Schild.<br \/>Foto: Lea Herbst<\/p><\/div>\n<p>So entstand im Laufe der Jahre die Tradition, nach der Wallfahrt eine s\u00fc\u00dfe Erinnerung mit nach Hause zu nehmen. Kein Wunder also, dass Joseph Gerlich bereits 1842 in Wartha ein entsprechendes Unternehmen gr\u00fcndete. Aus einer kleinen Verkaufsbude entwickelte sich der Betrieb bis 1914 zu einem Gesch\u00e4ft in einem vierst\u00f6ckigen Mietshaus.<\/p>\n<p>Mit dem Zweiten Weltkrieg endete diese Tradition jedoch vorerst. Die Besitzer der Lebkuchenbetriebe, die davon ihren Lebensunterhalt bestritten, wurden nach Deutschland vertrieben. Die Rezepte wurden \u00fcber viele Jahre hinweg streng geh\u00fctet, sodass die Herstellung der traditionellen Lebkuchen zun\u00e4chst in Vergessenheit geriet.<\/p>\n<div id=\"attachment_82751\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-82751\" class=\"size-large wp-image-82751\" src=\"https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/pierniki-w-srodku-piernikarni-1024x768.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/pierniki-w-srodku-piernikarni-1024x768.jpeg 1024w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/pierniki-w-srodku-piernikarni-300x225.jpeg 300w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/pierniki-w-srodku-piernikarni-768x576.jpeg 768w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/pierniki-w-srodku-piernikarni-1536x1152.jpeg 1536w, https:\/\/neueswochenblatt.pl\/wp-content\/uploads\/2026\/07\/pierniki-w-srodku-piernikarni.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-82751\" class=\"wp-caption-text\">Die Lebkuchen im Gesch\u00e4ft, sorgf\u00e4ltig verpackt.<br \/>Foto: Lea Herbst<\/p><\/div>\n<p>Erst als Johanna Prause, eine Nachfahrin der Familie Gerlich, die alten Rezepte im Jahr 2015 f\u00fcr die Herstellung der kleinen Lebkuchen weitergab, konnte diese Tradition wiederbelebt werden. Heute wird die Geschichte der Warthaer Lebkuchen in dem Gesch\u00e4ft Bardzkie Pierniki am Marktplatz fortgef\u00fchrt.<\/p>\n<p>&nbsp;<\/p>\n<h2>Wie es endete \u2026 und wie es weitergeht<\/h2>\n<p>Zum Abschluss der Wallfahrt versammelten sich die Teilnehmer noch einmal vor der Kirche, um gemeinsam zu musizieren und zu singen. Anschlie\u00dfend entstand ein Gruppenfoto \u2013 auch wenn darauf leider nicht alle Teilnehmer der Feierlichkeiten zu sehen sind.<\/p>\n<p>Die Pilger verabschiedeten sich mit der Vorfreude auf die n\u00e4chste gemeinsame Wallfahrt nach Albendorf.<\/p>\n<p>Eines wurde an diesem Tag deutlich: Die Wallfahrt der deutschen Minderheit nach Wartha ist nicht nur ein Ausdruck des Glaubens, sondern auch ein Ort der Begegnung, des Erinnerns und der Pflege gemeinsamer Traditionen. Sie verbindet Menschen verschiedener Generationen und zeigt, dass Sprache, Kultur und Glaube auch nach vielen Jahrzehnten weiterhin lebendig bleiben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Vor \u00fcber 750 Jahren wurde der Marienkult in Wartha erstmals urkundlich erw\u00e4hnt. Im Laufe der Jahrhunderte entwickelte sich die Tradition, zur Wallfahrtskirche Mari\u00e4 Heimsuchung zu pilgern. Viele Menschen nahmen weite Wege auf sich, um diesen besonderen Ort zu besuchen. Der Grund daf\u00fcr ist die \u00fcber 1000 Jahre alte Marienfigur, der zahlreiche Wunder zugeschrieben werden. [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":82762,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4225],"tags":[6499,8982,9384,9383,9385,7223,9093,9270,5909],"redaktor":[9382],"class_list":["post-82744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kirche-de","tag-glaube-de","tag-kirche-de","tag-mariae-heimsuchung","tag-orgel","tag-pilger","tag-verband-der-deutschen-sozial-kulturellen-gesellschaften-in-polen-de","tag-wallfahrt-de","tag-wartha-de","tag-zweiter-weltkrieg-de","redaktor-lea-herbst"],"acf":[],"_links":{"self":[{"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/posts\/82744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/comments?post=82744"}],"version-history":[{"count":3,"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/posts\/82744\/revisions"}],"predecessor-version":[{"id":82764,"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/posts\/82744\/revisions\/82764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/media\/82762"}],"wp:attachment":[{"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/media?parent=82744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/categories?post=82744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/tags?post=82744"},{"taxonomy":"redaktor","embeddable":true,"href":"https:\/\/neueswochenblatt.pl\/de\/wp-json\/wp\/v2\/redaktor?post=82744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}